{"id":137,"date":"2017-07-21T15:45:52","date_gmt":"2017-07-21T14:45:52","guid":{"rendered":"http:\/\/www.coherens.com\/site\/?p=137"},"modified":"2017-07-24T18:39:29","modified_gmt":"2017-07-24T17:39:29","slug":"le-temps-des-vacances","status":"publish","type":"post","link":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/","title":{"rendered":"Le temps des vacances"},"content":{"rendered":"<header class=\"post-header title-container fix\">\n<div class=\"title\"><\/div>\n<\/header>\n<div class=\"entry-container fix\">\n<div class=\"entry fix\">\n<div class=\"linkedin_share_container\">En train de boucler vos valises ?<\/div>\n<p>Avant de partir, je vous propose de\u00a0lire le dossier publi\u00e9 durant l&rsquo;\u00e9t\u00e9 2015 sur \u00ab\u00a0Le cerveau en vacances\u00a0\u00bb par Jean-Philippe Lachaux.<br \/>\n\u00ab\u00a0Comment bien se reposer la t\u00eate pendant les vacances\u00a0? Les neuroscientifiques ont d\u00e9couvert que notre cerveau r\u00e9organise enti\u00e8rement son activit\u00e9 durant cette p\u00e9riode, et qu\u2019un s\u00e9jour r\u00e9ussi doit en tenir compte\u00a0!\u00a0\u00bb<br \/>\n<a href=\"http:\/\/www.cerveauetpsycho.fr\/ewb_pages\/a\/article-le-cerveau-en-vacances-35450.php\" target=\"_blank\" rel=\"noopener\">Le cerveau en vacances<\/a><\/p>\n<p>Quand nous nous mettons en \u00ab\u00a0vacances\u00a0\u00bb, nous permettons \u00e0 notre cerveau de recharger ses \u00ab\u00a0ressources mentales\u00a0\u00bb \u00e9puis\u00e9es par l\u2019hyper vigilance que nous lui imposons le restant de l\u2019ann\u00e9e. Mais contrairement \u00e0 ce que nous pouvons spontan\u00e9ment penser, le cerveau ne se met pas au repos et va, en l\u2019absence d\u2019objectifs multiples, intenses, n\u00e9cessitant toute notre attention, se mettre en mode par d\u00e9faut. Ce mode du \u00ab\u00a0vagabondage\u00a0\u00bb que vous avez parfois observ\u00e9, est celui qui vous permet aussi des associations fertiles, des d\u00e9couvertes inattendues\u2026 Sauf que, sans sujet sur lequel porter votre attention, ce mode peut vous entra\u00eener \u00e0 la longue dans de la rumination st\u00e9rile.<\/p>\n<p>Alors, nous conseille Jean-Philippe Lachaux, coupez s\u00e9rieusement le lien professionnel et proposez-vous des activit\u00e9s c\u00e9r\u00e9brales \u00ab\u00a0douces\u00a0\u00bb, une \u00e0 la fois, sans enjeux d\u2019exploit ou de performance intense.<\/p>\n<p>Vous allez me dire, impossible de me d\u00e9connecter totalement. Et m\u00eame si je le pouvais, en partant sur une \u00eele d\u00e9serte coup\u00e9e du WiFi et de la 4G, je serais inquiet de savoir ce qui se passe.<\/p>\n<p><strong>Avant de partir, prenez le temps de pr\u00e9parer vos vacances\u00a0<\/strong><\/p>\n<ul>\n<li>faites la\u00a0liste des \u00ab to do \u00bb et des \u00ab sujets chauds \u00bb pour la rentr\u00e9e\u2026. enfermez cette liste soigneusement dans votre\u00a0bureau\u2026. \u00a0laissez l\u00e0 derri\u00e8re vous et oubliez l\u00e0. Vous ferez l\u2019\u00e9conomie d\u2019une vigilance inutile pendant vos vacances<\/li>\n<li>informez\u00a0vos coll\u00e8gues proches ou collaborateurs de \u00ab\u00a0permanence\u00a0\u00bb \u00a0des sujets urgents qui peuvent arriver et laissez-leur les informations utiles, cela leur \u00e9vitera trop de surprise, et vous \u00e9vitera de l\u2019inqui\u00e9tude st\u00e9rile<\/li>\n<li>si vous avez un t\u00e9l\u00e9phone \u00ab\u00a0pro\u00a0\u00bb et un t\u00e9l\u00e9phone \u00ab\u00a0perso\u00a0\u00bb, laissez le premier au fond de votre valise et donnez votre N\u00b0 \u00ab\u00a0perso\u00a0\u00bb \u00e0 quelques personnes de confiance qui pourront vous appeler en cas de sujet important et urgent<\/li>\n<li>cr\u00e9ez-vous une adresse sur une messagerie \u00ab\u00a0perso-pro\u00a0\u00bb, que vous communiquerez \u00e0 quelques personnes pour vous \u00a0envoyer un message court en cas d\u2019urgence, et que vous r\u00e9serverez \u00e0 cet usage pour qu\u2019elle ne soit pas envahie \u2026. ne soyez pas d\u00e9\u00e7u si aucun mail ne vient vous mobiliser, c\u2019est que tout va bien<\/li>\n<li>pensez \u00e0 mettre le rituel message d\u2019absence sur votre messagerie mail, en indiquant la personne que l\u2019on peut solliciter\u00a0en cas d\u2019absence\u2026. d\u00e9sactivez la notification de message, cachez soigneusement l\u2019ic\u00f4ne de votre messagerie professionnelle sur votre t\u00e9l\u00e9phone pro (si vous n\u2019en avez qu\u2019un) pour ne pas \u00eatre tent\u00e9 d\u2019aller y faire un tour<\/li>\n<li>et si \u00e0 l\u2019occasion d\u2019un vagabondage c\u00e9r\u00e9bral, \u00a0un oubli ou une id\u00e9e pro pointent \u00e0 l\u2019horizon, notez-l\u00e0 dans un petit calepin\u2026 vous les retrouverez \u00e0 la rentr\u00e9e<\/li>\n<\/ul>\n<p>Vous \u00eates \u00ab\u00a0off\u00a0\u00bb, vous pouvez respirer, partir l\u00e9ger avec quelques id\u00e9es d\u2019activit\u00e9s sympa\u2026 une occasion peut-\u00eatre de renouer avec des sujets d\u2019int\u00e9r\u00eats ou des loisirs\u00a0que vous appr\u00e9ciez avant\u2026. avant que vos responsabilit\u00e9s\u00a0ne vous embarquent loin\u2026 Vous pourrez peut-\u00eatre y trouver suffisamment de plaisir pour les conserver \u00e0 la rentr\u00e9e.<\/p>\n<p>Je vous souhaite de tr\u00e8s bonnes vacances, avec plein de moments de bonheur en famille, entre amis\u2026 et plein de moments de bonheur de \u00ab rien \u00bb.<\/p>\n<p>Premi\u00e8re publication en juillet 2015<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En train de boucler vos valises ? Avant de partir, je vous propose de\u00a0lire le dossier publi\u00e9 durant l&rsquo;\u00e9t\u00e9 2015 sur \u00ab\u00a0Le cerveau en vacances\u00a0\u00bb par Jean-Philippe Lachaux. \u00ab\u00a0Comment bien se reposer la t\u00eate pendant les vacances\u00a0? Les neuroscientifiques ont d\u00e9couvert que notre cerveau r\u00e9organise enti\u00e8rement son activit\u00e9 durant cette p\u00e9riode, et qu\u2019un s\u00e9jour r\u00e9ussi &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/\">Continue reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[19,10],"class_list":["post-137","post","type-post","status-publish","format-standard","hentry","category-dirigeants","category-neurosciences","tag-dirigeant","tag-neurosciences","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le temps des vacances - COHeRenS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le temps des vacances - COHeRenS\" \/>\n<meta property=\"og:description\" content=\"En train de boucler vos valises ? Avant de partir, je vous propose de\u00a0lire le dossier publi\u00e9 durant l&rsquo;\u00e9t\u00e9 2015 sur \u00ab\u00a0Le cerveau en vacances\u00a0\u00bb par Jean-Philippe Lachaux. \u00ab\u00a0Comment bien se reposer la t\u00eate pendant les vacances\u00a0? Les neuroscientifiques ont d\u00e9couvert que notre cerveau r\u00e9organise enti\u00e8rement son activit\u00e9 durant cette p\u00e9riode, et qu\u2019un s\u00e9jour r\u00e9ussi &hellip; Continue reading\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/\" \/>\n<meta property=\"og:site_name\" content=\"COHeRenS\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-21T14:45:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-24T17:39:29+00:00\" \/>\n<meta name=\"author\" content=\"bdubreucq\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bdubreucq\" \/>\n<meta name=\"twitter:site\" content=\"@bdubreucq\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"bdubreucq\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/\"},\"author\":{\"name\":\"bdubreucq\",\"@id\":\"https:\\\/\\\/www.coherens.com\\\/#\\\/schema\\\/person\\\/d31471db904c4a8b9015b67b90914574\"},\"headline\":\"Le temps des vacances\",\"datePublished\":\"2017-07-21T14:45:52+00:00\",\"dateModified\":\"2017-07-24T17:39:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/\"},\"wordCount\":631,\"commentCount\":0,\"keywords\":[\"dirigeant\",\"Neurosciences\"],\"articleSection\":[\"Dirigeants\",\"Neurosciences\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/\",\"url\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/\",\"name\":\"Le temps des vacances - COHeRenS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coherens.com\\\/#website\"},\"datePublished\":\"2017-07-21T14:45:52+00:00\",\"dateModified\":\"2017-07-24T17:39:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.coherens.com\\\/#\\\/schema\\\/person\\\/d31471db904c4a8b9015b67b90914574\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/2017\\\/07\\\/21\\\/le-temps-des-vacances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.coherens.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le temps des vacances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coherens.com\\\/#website\",\"url\":\"https:\\\/\\\/www.coherens.com\\\/\",\"name\":\"COHeRenS\",\"description\":\"LE POTENTIEL HUMAIN AU COEUR DE VOTRE PERFORMANCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coherens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.coherens.com\\\/#\\\/schema\\\/person\\\/d31471db904c4a8b9015b67b90914574\",\"name\":\"bdubreucq\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57f16d862d53fcf4c015208c96c33dfb360122603756fb47d8ee9f1ec8482485?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57f16d862d53fcf4c015208c96c33dfb360122603756fb47d8ee9f1ec8482485?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57f16d862d53fcf4c015208c96c33dfb360122603756fb47d8ee9f1ec8482485?s=96&d=mm&r=g\",\"caption\":\"bdubreucq\"},\"url\":\"https:\\\/\\\/www.coherens.com\\\/index.php\\\/author\\\/bdubreucq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le temps des vacances - COHeRenS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/","og_locale":"fr_FR","og_type":"article","og_title":"Le temps des vacances - COHeRenS","og_description":"En train de boucler vos valises ? Avant de partir, je vous propose de\u00a0lire le dossier publi\u00e9 durant l&rsquo;\u00e9t\u00e9 2015 sur \u00ab\u00a0Le cerveau en vacances\u00a0\u00bb par Jean-Philippe Lachaux. \u00ab\u00a0Comment bien se reposer la t\u00eate pendant les vacances\u00a0? Les neuroscientifiques ont d\u00e9couvert que notre cerveau r\u00e9organise enti\u00e8rement son activit\u00e9 durant cette p\u00e9riode, et qu\u2019un s\u00e9jour r\u00e9ussi &hellip; Continue reading","og_url":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/","og_site_name":"COHeRenS","article_published_time":"2017-07-21T14:45:52+00:00","article_modified_time":"2017-07-24T17:39:29+00:00","author":"bdubreucq","twitter_card":"summary_large_image","twitter_creator":"@bdubreucq","twitter_site":"@bdubreucq","twitter_misc":{"\u00c9crit par":"bdubreucq","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/#article","isPartOf":{"@id":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/"},"author":{"name":"bdubreucq","@id":"https:\/\/www.coherens.com\/#\/schema\/person\/d31471db904c4a8b9015b67b90914574"},"headline":"Le temps des vacances","datePublished":"2017-07-21T14:45:52+00:00","dateModified":"2017-07-24T17:39:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/"},"wordCount":631,"commentCount":0,"keywords":["dirigeant","Neurosciences"],"articleSection":["Dirigeants","Neurosciences"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/","url":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/","name":"Le temps des vacances - COHeRenS","isPartOf":{"@id":"https:\/\/www.coherens.com\/#website"},"datePublished":"2017-07-21T14:45:52+00:00","dateModified":"2017-07-24T17:39:29+00:00","author":{"@id":"https:\/\/www.coherens.com\/#\/schema\/person\/d31471db904c4a8b9015b67b90914574"},"breadcrumb":{"@id":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.coherens.com\/index.php\/2017\/07\/21\/le-temps-des-vacances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.coherens.com\/"},{"@type":"ListItem","position":2,"name":"Le temps des vacances"}]},{"@type":"WebSite","@id":"https:\/\/www.coherens.com\/#website","url":"https:\/\/www.coherens.com\/","name":"COHeRenS","description":"LE POTENTIEL HUMAIN AU COEUR DE VOTRE PERFORMANCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coherens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.coherens.com\/#\/schema\/person\/d31471db904c4a8b9015b67b90914574","name":"bdubreucq","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57f16d862d53fcf4c015208c96c33dfb360122603756fb47d8ee9f1ec8482485?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57f16d862d53fcf4c015208c96c33dfb360122603756fb47d8ee9f1ec8482485?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57f16d862d53fcf4c015208c96c33dfb360122603756fb47d8ee9f1ec8482485?s=96&d=mm&r=g","caption":"bdubreucq"},"url":"https:\/\/www.coherens.com\/index.php\/author\/bdubreucq\/"}]}},"_links":{"self":[{"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/posts\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":5,"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/posts\/137\/revisions"}],"predecessor-version":[{"id":500,"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/posts\/137\/revisions\/500"}],"wp:attachment":[{"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/media?parent=137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/categories?post=137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coherens.com\/index.php\/wp-json\/wp\/v2\/tags?post=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}